{"id":10796,"date":"2024-07-02T03:22:34","date_gmt":"2024-07-02T09:22:34","guid":{"rendered":"https:\/\/fonktown.es\/?p=10796"},"modified":"2024-10-08T04:19:34","modified_gmt":"2024-10-08T10:19:34","slug":"como-elegir-el-mejor-location-manager-en-espana","status":"publish","type":"post","link":"https:\/\/fonktown.es\/es\/como-elegir-el-mejor-location-manager-en-espana\/","title":{"rendered":"C\u00f3mo elegir el mejor location manager en Espa\u00f1a"},"content":{"rendered":"[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]A la hora de llevar a cabo una producci\u00f3n audiovisual se deben cuidar muchos detalles para que el resultado final refleje bien lo indicado en el gui\u00f3n. Uno de los elementos m\u00e1s importantes para esto es la <strong>elecci\u00f3n de las localizaciones adecuadas,<\/strong> es aqu\u00ed cuando entra en juego la figura del <em><strong>location manager<\/strong><\/em>.<\/p>\n<p><strong>Elegir bien una localizaci\u00f3n lo es todo en una producci\u00f3n<\/strong>, por eso es clave tener un criterio \u00f3ptimo en la selecci\u00f3n de un <em>location manager<\/em> para tu producci\u00f3n audiovisual.<\/p>\n<p><strong>\u00bfQuieres saber c\u00f3mo elegir el mejor <em>location manager<\/em> en Espa\u00f1a<\/strong>?\u00a0\u00a1Sigue leyendo y te lo contamos![\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb advanced_gradient_angle=\u00bb0&#8243; overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb top_margin=\u00bb4%\u00bb bottom_margin=\u00bb8%\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb][nectar_scrolling_text scroll_direction=\u00bbltr\u00bb scroll_speed=\u00bbslowest\u00bb text_color=\u00bb#0a0a0a\u00bb style=\u00bbtext_outline\u00bb outline_thickness=\u00bbultra-thin\u00bb text_repeat_number=\u00bb5&#8243; text_repeat_divider=\u00bbnone\u00bb overflow=\u00bbvisible\u00bb background_image_animation=\u00bbNone\u00bb custom_font_size=\u00bb9vw\u00bb custom_font_size_mobile=\u00bb15vw\u00bb]\n<h1><em>your perfect production #<\/em><\/h1>\n[\/nectar_scrolling_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h2>\u00bfQu\u00e9 es un location manager?<\/h2>\n<p>&nbsp;<\/p>\n<blockquote><p>Un<strong><em> location manager<\/em><\/strong> o jefe de localizaciones es la persona que se encarga de la<strong> b\u00fasqueda y gesti\u00f3n de todas las localizaciones<\/strong> necesarias para el rodaje <strong>de una producci\u00f3n audiovisual<\/strong>.<\/p><\/blockquote>\n<p>Aunque este perfil no sea tan conocido, <strong>la labor del <em>location manager<\/em> es fundamental<\/strong>, pues consigue traducir el gui\u00f3n de la producci\u00f3n cinematogr\u00e1fica en espacios reales.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h2>Funciones de un location manager en una producci\u00f3n audiovisual<\/h2>\n<p>Como hemos dicho anteriormente, un <em>location manager<\/em> tiene como <strong>funci\u00f3n principal la gesti\u00f3n de todas las localizaciones<\/strong> que forman parte de un rodaje. No obstante, para poder realizar esta gesti\u00f3n tambi\u00e9n lleva a cabo otras tareas m\u00e1s concretas a lo largo de todo el proceso.<\/p>\n<p>Estas son las <strong>funciones de un <em>location manager<\/em> en una producci\u00f3n audiovisual<\/strong>:<\/p>\n<ol>\n<li><a href=\"#estudio\"><strong>Estudio del gui\u00f3n y proyecto \u27a4<\/strong><\/a><\/li>\n<li><a href=\"#busqueda\"><strong>B\u00fasqueda de localizaciones \u27a4<\/strong><\/a><\/li>\n<li><a href=\"#eleccion\"><strong>Elecci\u00f3n de localizaciones \u27a4<\/strong><\/a><\/li>\n<li><a href=\"#tareas\"><strong>Tareas de gesti\u00f3n del rodaje \u27a4<\/strong><\/a><\/li>\n<li><a href=\"#control\"><strong>Control del estado del espacio tras el rodaje \u27a4<\/strong><\/a><\/li>\n<\/ol>\n<h3 id=\"estudio\">Estudio del gui\u00f3n y proyecto<\/h3>\n<p>El <strong>primer paso<\/strong> que debe tomar un<em> location manager<\/em> es <strong>estudiar a fondo el gui\u00f3n<\/strong>, pues debe conocer con todo detalle el proyecto audiovisual para poder seleccionar las localizaciones perfectas para este.<\/p>\n<p>Adem\u00e1s, durante esta fase el <em>location manager<\/em> tambi\u00e9n <strong>se re\u00fane con el director y todo el departamento de producci\u00f3n<\/strong> para <strong>poner en com\u00fan las ideas y detalles<\/strong> que tienen cada uno en la cabeza acerca de la producci\u00f3n audiovisual. De hecho, es muy importante que se mantenga la comunicaci\u00f3n entre estos miembros durante todo el proceso.<\/p>\n<h3 id=\"busqueda\">B\u00fasqueda de localizaciones<\/h3>\n<p>La b\u00fasqueda de localizaciones es la <strong>funci\u00f3n principal de un <em>location manager<\/em><\/strong>. Para ello, no \u00fanicamente debe tener en cuenta si el lugar es bonito o si se acopla al gui\u00f3n, sino tambi\u00e9n otros aspectos como el calendario de trabajo y el presupuesto, pues el traslado del equipo a las distintas localizaciones supone un coste.<\/p>\n<p>Adem\u00e1s, toda<strong> esta b\u00fasqueda debe quedar documentada<\/strong> para posteriormente ponerlo en com\u00fan con el resto del equipo. Por eso, el <em>location manager<\/em> tambi\u00e9n se encarga de <strong>crear su propio directorio de localizaciones<\/strong> con sus correspondientes apuntes, fotograf\u00edas y direcciones.<\/p>\n<p>Muchas veces el <em>location manager<\/em> de una producci\u00f3n audiovisual <strong>acude a plataformas o directorios de localizaciones<\/strong> que disponen de una lista de lugares recomendados para rodajes a nivel nacional o provincial. Como, por ejemplo, la asociaci\u00f3n <a href=\"http:\/\/www.shootinginspain.info\/\" target=\"_blank\" rel=\"noopener\">Spain Film Comission<\/a> que cuenta con el apoyo del Ministerio de Cultura y Deporte del Gobierno de Espa\u00f1a.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10833 size-full\" src=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/location-manager-funciones-productora-audiovisual-fonktown-Espan\u0303a.jpg\" alt=\"location manager funciones productora audiovisual Fonktown Espa\u00f1a\" width=\"800\" height=\"797\" srcset=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/location-manager-funciones-productora-audiovisual-fonktown-Espan\u0303a.jpg 800w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/location-manager-funciones-productora-audiovisual-fonktown-Espan\u0303a-80x80.jpg 80w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/location-manager-funciones-productora-audiovisual-fonktown-Espan\u0303a-768x765.jpg 768w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/location-manager-funciones-productora-audiovisual-fonktown-Espan\u0303a-500x498.jpg 500w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/location-manager-funciones-productora-audiovisual-fonktown-Espan\u0303a-100x100.jpg 100w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/location-manager-funciones-productora-audiovisual-fonktown-Espan\u0303a-140x140.jpg 140w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/location-manager-funciones-productora-audiovisual-fonktown-Espan\u0303a-350x350.jpg 350w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/h3>\n<h3 id=\"eleccion\">Elecci\u00f3n de localizaciones<\/h3>\n<p>Junto a la b\u00fasqueda de localizaciones, la elecci\u00f3n de estas es <strong>otra de las funciones principales de un <em>location manager<\/em><\/strong>, pues su decisi\u00f3n determinar\u00e1 el efecto final de la producci\u00f3n audiovisual.<\/p>\n<p>Una vez ya ha recopilado un abanico de lugares posibles en los que rodar, el<em> location manager<\/em> debe tener un<strong> criterio a la hora de seleccionar entre todas estas localizaciones<\/strong> para alcanzar buenos resultados.<\/p>\n<p>Como hemos dicho, m\u00e1s all\u00e1 del paisaje y lo adaptable al gui\u00f3n que pueda ser un lugar, un<em> location manager<\/em> debe elegir las localizaciones pensando en muchos otros aspectos. Como, por ejemplo, la <strong>accesibilidad, el nivel de ruido, los permisos e incentivos fiscales o las normativas de seguridad e higiene<\/strong>.<\/p>\n<h3 id=\"tareas\">Tareas de gesti\u00f3n del rodaje<\/h3>\n<p>Cuando ya se han seleccionado las localizaciones concretas que formar\u00e1n parte del rodaje, el <em>location manager<\/em> sigue jugando un papel fundamental en este. Puesto que, tambi\u00e9n lleva a cabo<strong> tareas de gesti\u00f3n relacionadas con las localizaciones del rodaje<\/strong>.<\/p>\n<p>En primer lugar, el <em>location manager<\/em> entrega previamente a todos los miembros del equipo una <strong>lista con la planificaci\u00f3n de las localizaciones<\/strong> en las que se va a rodar, con la fecha, la hora y las direcciones precisas. <strong>El<em> location manager<\/em> siempre es el primero en llegar a la localizaci\u00f3n<\/strong>\u00a0para gestionar y organizar todo antes de que llegue el resto del equipo.<\/p>\n<p>Adem\u00e1s, <em>el location manager<\/em> tambi\u00e9n puede ser el responsable de<strong> tramitar todos los permisos y solicitar los servicios p\u00fablicos<\/strong> de la zona, as\u00ed como la <strong>reserva de alojamiento, requisitos t\u00e9cnicos o el alquiler de equipo<\/strong>.<\/p>\n<h3 id=\"control\">Control del estado del espacio tras el rodaje<\/h3>\n<p>Al igual que un<em> location manager<\/em> debe ser el primero en llegar al lugar de rodaje, tambi\u00e9n<strong> debe ser el \u00faltimo en irse<\/strong>, ya que es el m\u00e1ximo encargado de <strong>asegurarse de que el espacio se queda en buen estado tras el rodaje<\/strong>.<\/p>\n<p>El <em>location manager<\/em> se ocupa de <strong>gestionar la limpieza de las localizaciones y subsanar los desperfectos<\/strong> que puedan haber quedado. As\u00ed pues, en caso de haber provocado da\u00f1os en el lugar, tambi\u00e9n se encarga de realizar un informe de estos y tramitarlo.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h2>Consejos para elegir el mejor location manager en Espa\u00f1a<\/h2>\n<p>L<strong>a labor del <em>location manager<\/em> es fundamental<\/strong> para obtener buenos resultados de la producci\u00f3n audiovisual. Es por eso que, al mismo tiempo, cobra tanta <strong>importancia escoger un buen profesional<\/strong> que adopte ese rol.<\/p>\n<p>A continuaci\u00f3n, te contamos algunos <strong>consejos para elegir el mejor <em>location manager<\/em> en Espa\u00f1a<\/strong>:<\/p>\n<ul>\n<li><strong>Conocimiento de la zona:<\/strong> Trat\u00e1ndose de un perfil como buscador de localizaciones, siempre va a ayudar que la persona conozca la zona, pues tendr\u00e1 mayor agilidad a la hora de moverse y no partir\u00e1 desde cero para la recopilaci\u00f3n de lugares.<\/li>\n<li><strong>Una persona activa y organizada:<\/strong> Las funciones de <em>location manager<\/em> requieren de una actitud activa que posibilite moverse de un lado a otro en b\u00fasqueda de localizaciones. As\u00ed como que el profesional sea muy organizado a la hora de gestionar tareas del rodaje como, por ejemplo, planificar el calendario, controlar el presupuesto o crear su directorio de localizaciones.<\/li>\n<li><strong>Experiencia:<\/strong> Como en todas las profesiones, siempre va a ser m\u00e1s recomendable contar con un profesional que tenga una larga trayectoria en el sector. En el caso de un <em>location manager<\/em> con mayor raz\u00f3n a\u00fan, pues habr\u00e1 mayor posibilidad de que disponga de una larga lista de lugares localizados para cualquier tipo de producci\u00f3n audiovisual.<\/li>\n<li><strong>Flexibilidad:<\/strong> La figura de <em>location manager<\/em> requiere de mucha flexibilidad, pues debe estar siempre presente durante los rodajes, incluso si se trata de horario nocturno. As\u00ed pues, esta profesi\u00f3n tambi\u00e9n conlleva muchos viajes por el pa\u00eds, por lo que la persona encargada de las localizaciones debe estar dispuesto a ello.<\/li>\n<li><strong>Amante de los viajes:<\/strong> En la misma l\u00ednea que el criterio de flexibilidad, si al profesional le gusta viajar siempre va a facilitar los traslados de un lado a otro. Adem\u00e1s, si previamente ha realizado muchos viajes dispondr\u00e1 tambi\u00e9n de una larga lista de localizaciones documentadas.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10828 size-full\" src=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/consejos-para-elegir-location-manager-.jpg\" alt=\"consejos para elegir location manager productora audiovisual Espa\u00f1a\" width=\"800\" height=\"1067\" srcset=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/consejos-para-elegir-location-manager-.jpg 800w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/consejos-para-elegir-location-manager--768x1024.jpg 768w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/consejos-para-elegir-location-manager--500x667.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h2>Qu\u00e9 location manager escoger seg\u00fan el proyecto audiovisual<\/h2>\n<p>Al igual que existen muchos tipos de proyectos audiovisuales, tambi\u00e9n hay ciertos profesionales dedicados a cada uno de ellos. Es por eso que, <strong>dependiendo del proyecto<\/strong> se requiere que el <em>location manager<\/em> tenga unas <strong>nociones audiovisuales m\u00e1s concretas<\/strong>.<\/p>\n<p>Por ejemplo, cu\u00e1ndo sale y se pone el sol en la zona, los permisos para volar drones, la posibilidad de contar con un parking cercano para muchos veh\u00edculos en producciones grandes o si el espacio escogido puede soportar aparatos de c\u00e1mara grandes como un Scorpio crane o un dolly.<\/p>\n<blockquote><p>Un<em> location manager<\/em> que ha trabajado en grandes producciones siempre va a tener m\u00e1s en cuenta todo el aspecto log\u00edstico.<\/p><\/blockquote>\n<p>Adem\u00e1s de las <strong>condiciones de la localizaci\u00f3n y el tama\u00f1o de la producci\u00f3n<\/strong>, en ocasiones es <strong>la tem\u00e1tica del proyecto audiovisual<\/strong> lo que requiere de un <em>location manager<\/em> especializado en grandes gestiones o no.<\/p>\n<p>Por ejemplo, para un <strong>documental de naturaleza<\/strong> lo m\u00e1s recomendable ser\u00e1 buscar un <em>location manager<\/em> que se conozca muy bien la monta\u00f1a de la zona, mientras que para una <strong>producci\u00f3n ubicada en barrios urbanos<\/strong> deber\u00e1s contar con otro tipo de <em>location manager<\/em> que ya tenga experiencia previa en este tipo de espacios.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h2>Qu\u00e9 tipo de localizaciones puedes encontrar en Espa\u00f1a<\/h2>\n<p><strong>Espa\u00f1a<\/strong> es un pa\u00eds <strong>ideal para rodajes cinematogr\u00e1ficos<\/strong>, ya que puedes optar entre una gran variedad de <strong>localizaciones de todo tipo<\/strong>. Desde paisajes rurales y zonas costeras paradisiacas, hasta ciudades futuristas que parecen sacadas de una pel\u00edcula de ciencia ficci\u00f3n.<\/p>\n<p>A pesar de que ya realizamos un art\u00edculo sobre <a href=\"https:\/\/fonktown.es\/es\/mejores-localizaciones\/\" target=\"_blank\" rel=\"noopener\">las 31 mejores localizaciones para rodajes en Espa\u00f1a,<\/a> en esta ocasi\u00f3n te explicamos a fondo los principales <strong>tipos de localizaciones que puedes encontrar en Espa\u00f1a<\/strong>:<\/p>\n<h3>Parques y zonas verdes<\/h3>\n<p>Espa\u00f1a cuenta con ciudades que contienen verdaderos <strong>oasis de vegetaci\u00f3n en medio del ambiente urbano<\/strong>. Estos parques y zonas verdes, adem\u00e1s de la est\u00e9tica y el aire fresco que aporta a los habitantes de la localidad, es un gran <strong>foco de atenci\u00f3n para producciones audiovisuales<\/strong>.<\/p>\n<p>Las zonas de vegetaci\u00f3n de Espa\u00f1a presentan muchas ventajas para el rodaje de pel\u00edculas, series, spots, etc; ya que, adem\u00e1s de servir como un espacio decorativo bonito, muchos de ellos tambi\u00e9n <strong>contienen muchos monumentos hist\u00f3ricos<\/strong> en su interior.<\/p>\n<p>Algunos de los <strong>parques y zonas verdes m\u00e1s reconocidos de Espa\u00f1a<\/strong> son el Antiguo Cauce del R\u00edo Turia de Valencia, el Parque del Retiro de Madrid y el Parque de Maria Luisa de Sevilla.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10807 aligncenter\" src=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/parque-del-retiro-madrid-location-manager.jpg\" alt=\"parque del retiro madrid location manager\" width=\"1000\" height=\"667\" srcset=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/parque-del-retiro-madrid-location-manager.jpg 1000w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/parque-del-retiro-madrid-location-manager-768x512.jpg 768w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/parque-del-retiro-madrid-location-manager-500x334.jpg 500w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/parque-del-retiro-madrid-location-manager-800x534.jpg 800w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/parque-del-retiro-madrid-location-manager-900x600.jpg 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/h2>\n<h3>Barrios y monumentos hist\u00f3ricos<\/h3>\n<p>Las ciudades de Espa\u00f1a destacan por un <strong>gran valor cultural e hist\u00f3rico<\/strong>, pues en muchas de ellas han convivido a lo largo de los a\u00f1os <strong>diferentes movimientos culturales<\/strong>. Es por eso mismo que cuentan con <strong>muchos monumentos hist\u00f3ricos reconocidos<\/strong>.<\/p>\n<p>Por ejemplo, la <strong>bas\u00edlica g\u00f3tica de Gaud\u00ed<\/strong> es considerada <strong>Patrimonio de la Humanidad<\/strong> y es uno de los grandes signos de la ciudad de Barcelona, y de Espa\u00f1a en general. Esto tiene como ventaja que con solo salir el monumento en una escena, el espectador ya entiende d\u00f3nde se ubica la historia. Es un lugar perfecto para rodajes cinematogr\u00e1ficos, pues adem\u00e1s de su belleza arquitect\u00f3nica, <strong>cuenta con mucho espacio para albergar todo tipo de equipo humano y material<\/strong>.<\/p>\n<p>Por otro lado, entre los <strong>barrios hist\u00f3ricos m\u00e1s reconocidos de Espa\u00f1a<\/strong> ideales para producciones audiovisuales se encuentran el Barrio del Carmen de Valencia, Malasa\u00f1a en Madrid y la Graci\u00e0 en Barcelona.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10813 aligncenter\" src=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/sagrada-familia-barcelona-location-manager.jpg\" alt=\"sagrada familia barcelona location manager\" width=\"800\" height=\"1200\" srcset=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/sagrada-familia-barcelona-location-manager.jpg 800w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/sagrada-familia-barcelona-location-manager-768x1152.jpg 768w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/sagrada-familia-barcelona-location-manager-500x750.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/h2>\n<h3>Paisajes rurales<\/h3>\n<p>Adem\u00e1s de zonas verdes en el n\u00facleo urbano, Espa\u00f1a cuenta con una gran cantidad de <strong>espacios de monta\u00f1a<\/strong> que son escogidos como <strong>escenarios de producciones audiovisuales<\/strong> de todo el mundo. Existen muchas <strong>zonas del pa\u00eds con una gran riqueza natural<\/strong>, algunos de los m\u00e1s destacados son el monasterio de Montserrat en Barcelona o el Puig Major en Mallorca.<\/p>\n<p>Por otro lado, m\u00e1s all\u00e1 de la <strong>gran cantidad de parajes naturales<\/strong> que hay, tambi\u00e9n son muy reclamados ciertos <strong>pueblos de la pen\u00ednsula con un gran encanto rural<\/strong>. Como, por ejemplo, Pe\u00f1\u00edscola, el cual tanto su paisaje como su centro hist\u00f3rico han sido escenario de muchos rodajes cinematogr\u00e1ficos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10867 size-full\" src=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/monaterio-montserrat-Mallorca-localizaciones-Espan\u0303a-production-company-Fonktown-Espan\u0303a.jpg\" alt=\"monasterio montserrat Mallorca location manager production company Fonktown Espa\u00f1a\" width=\"800\" height=\"533\" srcset=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/monaterio-montserrat-Mallorca-localizaciones-Espan\u0303a-production-company-Fonktown-Espan\u0303a.jpg 800w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/monaterio-montserrat-Mallorca-localizaciones-Espan\u0303a-production-company-Fonktown-Espan\u0303a-768x512.jpg 768w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/monaterio-montserrat-Mallorca-localizaciones-Espan\u0303a-production-company-Fonktown-Espan\u0303a-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3>Escenarios futuristas<\/h3>\n<p>Si est\u00e1s buscando un lugar con aire futurista para tu producci\u00f3n audiovisual, sin duda Espa\u00f1a es tu sitio. Concretamente, la localizaci\u00f3n futurista de Espa\u00f1a m\u00e1s destacada es la <strong>Ciudad de las Artes y las Ciencias, <\/strong>una de las localizaciones m\u00e1s famosas de la ciudad de Valencia que <strong>ha acogido multitud de rodajes de pel\u00edculas, series, shootings y spots<\/strong>.<\/p>\n<p>Se trata de un <strong>complejo arquitect\u00f3nico<\/strong> dise\u00f1ado por Santiago Calatrava que se caracteriza por el <strong>estilo moderno y futurista<\/strong> reflejado en sus estructuras y caminos hechos de trencad\u00eds blanco y divididos por unos grandes estanques de agua cristalina en medio.<\/p>\n<p>No obstante, a lo largo del pa\u00eds tambi\u00e9n puedes encontrar <strong>otras localizaciones futuristas<\/strong> como: el Hotel Vela y la Torre MareNostrum de Barcelona o los edificios singulares del Parque Tecnol\u00f3gico de \u00c1lava.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10809 aligncenter\" src=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ciudad-artes-y-ciencias-valencia-location-manager.jpg\" alt=\"ciudad de las artes y las ciencias location manager\" width=\"1000\" height=\"662\" srcset=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ciudad-artes-y-ciencias-valencia-location-manager.jpg 1000w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ciudad-artes-y-ciencias-valencia-location-manager-768x508.jpg 768w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ciudad-artes-y-ciencias-valencia-location-manager-500x331.jpg 500w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ciudad-artes-y-ciencias-valencia-location-manager-800x530.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/h2>\n<h3>Islas y costas paradisiacas<\/h3>\n<p>\u00bfQui\u00e9n dijo que para rodar en una playa de ensue\u00f1o era necesario ir al Caribe?<\/p>\n<p>Espa\u00f1a cuenta con un gran n\u00famero de <strong>calas y playas paradis\u00edacas ideales para rodar producciones audiovisuales<\/strong>. Adem\u00e1s, estas se encuentran rodeadas de un entorno repleto de vegetaci\u00f3n y carreteras con vistas que constituyen un <strong>paisaje id\u00edlico<\/strong>.<\/p>\n<p>Las calas m\u00e1s se\u00f1aladas en Espa\u00f1a se encuentran en las <strong>Islas Baleares, <\/strong>entre las que destacan\u00a0el Cabo de Formentor de Mallorca, el Puerto de Mah\u00f3n de Menorca, la cala Es Vedr\u00e0 de Ibiza y la playa Ses Illetes de Formentera.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10811 aligncenter\" src=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ses-illetes-formentera-location-manager.jpg\" alt=\"ses illetes formentera location manager\" width=\"1000\" height=\"1333\" srcset=\"https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ses-illetes-formentera-location-manager.jpg 1000w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ses-illetes-formentera-location-manager-768x1024.jpg 768w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ses-illetes-formentera-location-manager-500x667.jpg 500w, https:\/\/fonktown.es\/wp-content\/uploads\/2023\/03\/ses-illetes-formentera-location-manager-800x1066.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h2>\u00bfPor qu\u00e9 elegir a Fonktown como el location manager de tu producci\u00f3n?<\/h2>\n<p>Si buscas un profesional que busque y gestione las localizaciones de tu producci\u00f3n audiovisual, puedes contar con nuestro <em>location manager<\/em> de <strong>Fonktown,<\/strong> ya que destacamos por ser <strong>empresa l\u00edder de servicios de producci\u00f3n en Espa\u00f1a<\/strong>.<\/p>\n<p>Estas son las razones que te damos de <strong>por qu\u00e9 elegir el <em>location manage<\/em>r de Fonktown Espa\u00f1a<\/strong>:<\/p>\n<ul>\n<li><strong>Experiencia en <em>scouting<\/em>:<\/strong> Fonktown cuenta con un experimentado equipo especializado en <a href=\"https:\/\/fonktown.es\/es\/scouting\/\" target=\"_blank\" rel=\"noopener\"><em>scouting<\/em><\/a>. Este servicio est\u00e1 centrado en encontrar las mejores localizaciones para producciones audiovisuales en Espa\u00f1a.<\/li>\n<li><strong>Conocimiento local: <\/strong>Los <em>locations managers<\/em> de Fonktown tienen una larga trayectoria profesional en Espa\u00f1a, por lo que conocen a fondo todo el territorio nacional y facilita en gran medida la b\u00fasqueda y gesti\u00f3n de localizaciones.<\/li>\n<li><strong>Servicio en toda Espa\u00f1a:<\/strong> Fonktown trabaja con su equipo de <em>location managers<\/em> alrededor de todo el pa\u00eds. Adem\u00e1s, ha trabajado durante a\u00f1os por todo el territorio nacional y podr\u00e1 ofrecerte las mejores localizaciones de Espa\u00f1a para tu proyecto.<\/li>\n<li><strong>Todo tipo de proyecto audiovisual:<\/strong> El <em>location manager<\/em> de Fonktown tiene una larga experiencia que le ha permitido poder desarrollar sus funciones en distintos tipos de piezas audiovisuales. No importa si tu proyecto se trata de un anuncio, una pel\u00edcula, una serie de televisi\u00f3n o un documental, \u00e9l buscar\u00e1 la localizaci\u00f3n perfecta para ti.<\/li>\n<li><strong>Acceso directo a las autoridades gubernamentales:<\/strong> Debido a su amplia trayectoria y trabajo cont\u00ednuo en Espa\u00f1a, Fonktown tiene contacto con todas las autoridades gubernamentales y puede conseguir todos los permisos y tr\u00e1mites necesarios para las producciones audiovisuales de la forma m\u00e1s r\u00e1pida posible.<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h2>Contacta con nuestro location manager en Espa\u00f1a<\/h2>\n<p>Si te has decidido a contratar un <strong><em>location manager<\/em> para tu producci\u00f3n audiovisual<\/strong>, puedes contactar con nuestro <em>location manager<\/em> en Espa\u00f1a. \u00c9l te ayudar\u00e1 en la b\u00fasqueda y gesti\u00f3n de las mejores localizaciones para tu rodaje.<\/p>\n<p><strong>Rellena el siguiente formulario<\/strong> y ponte en contacto con nosotros:[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb advanced_gradient_angle=\u00bb0&#8243; overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9650-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"9650\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/posts\/10796#wpcf7-f9650-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9650\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9650-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:9650,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;repeater_remove_button&quot;:&quot;bottom&quot;}}\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col span_6\">\n\t\t<div class=\"minimal-form-input\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col span_6 col_last\">\n\t\t<div class=\"minimal-form-input\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-145\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"text\" name=\"tel-145\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col span_12 col_last\">\n\t\t<div class=\"minimal-form-input\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"text\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col span_12 col_last\">\n\t\t<div class=\"minimal-form-input\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-56\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Mensaje\" value=\"\" type=\"text\" name=\"text-56\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col span_12 col_last\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-consent\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"your-consent\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He leido, acepto y entiendo la <a href=\"\/politica-de-privacidad\/\">Pol\u00edtica de Privacidad<\/a>, d\u00e1ndome por informado\/a de todo lo que en ellas se dispone.<\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><script type='text\/javascript'>\n\n\t\t\t\t\t\tif(contactform === undefined){\n\t\t\t\t\t\t\tvar contactform = [];\n\t\t\t\t\t\t}\n\t\t\t\t\t\tvar innerVal = [9650,'mail_sent_ok','Thank you for your message. It has been sent.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'mail_sent_ng','There was an error trying to send your message. Please try again later.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'validation_error','One or more fields have an error. Please check and try again.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'spam','There was an error trying to send your message. Please try again later.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'accept_terms','You must accept the terms and conditions before sending your message.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'invalid_required','The field is required.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'invalid_too_long','The field is too long.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'invalid_too_short','The field is too short.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'upload_failed','There was an unknown error uploading the file.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'upload_file_type_invalid','You are not allowed to upload files of this type.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'upload_file_too_large','The file is too big.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'upload_failed_php_error','There was an error uploading the file.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'invalid_date','The date format is incorrect.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'date_too_early','The date is before the earliest one allowed.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'date_too_late','The date is after the latest one allowed.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'invalid_number','The number format is invalid.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'number_too_small','The number is smaller than the minimum allowed.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'number_too_large','The number is larger than the maximum allowed.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'quiz_answer_not_correct','The answer to the quiz is incorrect.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'invalid_email','The e-mail address entered is invalid.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'invalid_url','The URL is invalid.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'invalid_tel','The telephone number is invalid.'];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\tvar innerVal = [9650,'gdpr',''];\n\t\t\t\t\t\tcontactform.push(innerVal);\n\t\t\t\t\t\t<\/script><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"59\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10816,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100],"tags":[],"class_list":["post-10796","post","type-post","status-publish","format-standard","has-post-thumbnail","category-blog-2"],"_links":{"self":[{"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/posts\/10796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/comments?post=10796"}],"version-history":[{"count":68,"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/posts\/10796\/revisions"}],"predecessor-version":[{"id":10838,"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/posts\/10796\/revisions\/10838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/media\/10816"}],"wp:attachment":[{"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/media?parent=10796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/categories?post=10796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fonktown.es\/es\/wp-json\/wp\/v2\/tags?post=10796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}